{"id":3071,"date":"2024-08-09T11:01:18","date_gmt":"2024-08-09T11:01:18","guid":{"rendered":"https:\/\/agroreforest.eu\/?p=3071"},"modified":"2024-08-09T11:01:19","modified_gmt":"2024-08-09T11:01:19","slug":"high-level-dialogue-on-scaling-up-agroforestry","status":"publish","type":"post","link":"https:\/\/agroreforest.eu\/fr\/high-level-dialogue-on-scaling-up-agroforestry\/","title":{"rendered":"Dialogue de haut niveau sur l'expansion de l'agroforesterie"},"content":{"rendered":"<p>Le 23 juillet 2024, Simon Swatek (Universit\u00e9 de Bonn) a particip\u00e9 \u00e0 la conf\u00e9rence de l'Union europ\u00e9enne sur le th\u00e8me de l'\u00e9galit\u00e9 des chances pour les femmes et les hommes. <a href=\"https:\/\/www.fao.org\/home\/en\/\">Organisation des Nations unies pour l'alimentation et l'agriculture (FAO)<\/a> sur l'intensification de l'agroforesterie. Ce dialogue de haut niveau s'inscrivait dans le cadre du <a href=\"https:\/\/www.fao.org\/forestry\/committee-on-forestry\/world-forest-week-side-events\/en\">9<sup>th<\/sup> Semaine mondiale des for\u00eats<\/a>qui s'est tenue sous la devise \"Acc\u00e9l\u00e9rer les solutions foresti\u00e8res gr\u00e2ce \u00e0 l'innovation\". Les intervenants ont discut\u00e9 du potentiel de transformation des <strong>agroforesterie<\/strong> dans le secteur agroalimentaire, en mettant l'accent sur les opportunit\u00e9s, les le\u00e7ons tir\u00e9es des projets pass\u00e9s et en cours, et les efforts actuels pour soutenir l'expansion nationale.<\/p>\n\n\n\n<p>Parmi les intervenants figuraient non seulement des d\u00e9cideurs politiques et des membres de la FAO, mais aussi des agriculteurs qui ont fait part de leurs exp\u00e9riences en mati\u00e8re d'agroforesterie. Par exemple, M. Michael Taylor, \u00e9leveur australien de moutons et de bovins, a fait part de son exp\u00e9rience en mati\u00e8re d'agroforesterie. <strong>L'exploitation agricole a r\u00e9ussi \u00e0 faire passer le couvert v\u00e9g\u00e9tal de 5% \u00e0 plus de 23% en 37 ans.<\/strong>Il a soulign\u00e9 l'importance des droits fonciers pour rendre la plantation d'arbres possible et rentable. Il a soulign\u00e9 l'importance des droits fonciers pour rendre la plantation d'arbres possible et rentable et a insist\u00e9 sur la n\u00e9cessit\u00e9 d'apprendre de la sylviculture et de l'\u00e9cologie pour planifier et g\u00e9rer des syst\u00e8mes agroforestiers r\u00e9ussis.<\/p>\n\n\n\n<p>D'autres intervenants, tels que Elaine Springgay de la FAO, ont discut\u00e9 de la question de l'acc\u00e8s \u00e0 l'eau potable. <strong>importance de l'acc\u00e8s au march\u00e9<\/strong>, <strong>la cr\u00e9ation de la cha\u00eene de valeur, le financement et le soutien des pouvoirs publics<\/strong>. Elle a soulign\u00e9 que l'agroforesterie ne consiste pas simplement \u00e0 planter des arbres dans les fermes, mais \u00e0 int\u00e9grer des plantes vivaces ligneuses dans les exploitations agricoles d'une mani\u00e8re \u00e9conomiquement viable.<\/p>\n\n\n\n<p>Des repr\u00e9sentants des gouvernements du Costa Rica, de l'Inde et de Sao Tom\u00e9-et-Principe ont fait part de leurs succ\u00e8s dans l'utilisation des technologies de l'information et de la communication (TIC). <strong>les pratiques agroforesti\u00e8res pour la restauration des paysages, l'arr\u00eat de la d\u00e9forestation et la r\u00e9duction de la pression sur les for\u00eats existantes<\/strong>.<\/p>\n\n\n\n<p>Tous les intervenants ont soulign\u00e9 l'importance d'une approche multipartite, int\u00e9grant les propri\u00e9taires fonciers et les gestionnaires, les universit\u00e9s et les centres de recherche, ainsi que le secteur priv\u00e9 (par exemple, les p\u00e9pini\u00e8res) dans la conversation et faisant d'eux les cibles de politiques de soutien.<\/p>\n\n\n\n<p>Les repr\u00e9sentants des gouvernements europ\u00e9ens d'Autriche et d'Irlande ont fait part de leurs projets visant \u00e0 mettre en place des programmes \u00e9ducatifs pour les agriculteurs et des m\u00e9canismes de financement pour l'agroforesterie. <strong>L'agroforesterie est consid\u00e9r\u00e9e comme une composante essentielle d'un paysage r\u00e9silient et productif.<\/strong> Les agriculteurs irlandais peuvent d\u00e9j\u00e0 b\u00e9n\u00e9ficier de paiements pour l'agroforesterie dans le cadre du r\u00e9gime de paiement pour l'agriculture biologique, tandis que les agriculteurs autrichiens recevront une aide financi\u00e8re \u00e0 partir de 2025.<\/p>\n\n\n\n<p>ReForest se consacre \u00e0 l'expansion des pratiques agroforesti\u00e8res \u00e0 travers l'Europe. Nous sommes reconnaissants d'avoir eu l'occasion d'obtenir des informations pr\u00e9cieuses de la part de parties prenantes activement impliqu\u00e9es dans la promotion de l'agroforesterie. Ces discussions et ces exp\u00e9riences nous permettront d'informer et d'am\u00e9liorer nos efforts pour promouvoir des solutions agroforesti\u00e8res durables et innovantes dans toute la r\u00e9gion.<\/p>","protected":false},"excerpt":{"rendered":"<p>On July 23rd, 2024, Simon Swatek (University of Bonn) attended the Food and Agriculture Organization\u2019s (FAO) event on scaling up agroforestry. This high-level dialogue was part of the 9th World [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/posts\/3071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/comments?post=3071"}],"version-history":[{"count":1,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/posts\/3071\/revisions"}],"predecessor-version":[{"id":3073,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/posts\/3071\/revisions\/3073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/media\/3072"}],"wp:attachment":[{"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/media?parent=3071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/categories?post=3071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agroreforest.eu\/fr\/wp-json\/wp\/v2\/tags?post=3071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}