{"id":3439,"date":"2024-11-15T10:42:37","date_gmt":"2024-11-15T10:42:37","guid":{"rendered":"https:\/\/agroreforest.eu\/?p=3439"},"modified":"2024-11-15T10:42:38","modified_gmt":"2024-11-15T10:42:38","slug":"reforest-at-cop29-financing-agroforestry-for-a-sustainable-future","status":"publish","type":"post","link":"https:\/\/agroreforest.eu\/es\/reforest-at-cop29-financing-agroforestry-for-a-sustainable-future\/","title":{"rendered":"ReForest en la COP29: Financiaci\u00f3n de la agrosilvicultura para un futuro sostenible"},"content":{"rendered":"<p>En un <a href=\"https:\/\/rea.ec.europa.eu\/news\/vulnerability-viability-how-eu-funded-projects-help-regions-climate-crisis-frontline-2024-10-31_en\">art\u00edculo reciente<\/a>El <a href=\"https:\/\/rea.ec.europa.eu\/\">Agencia Ejecutiva Europea de Investigaci\u00f3n (REA)<\/a> destaca el papel vital de los proyectos financiados por la UE para allanar el camino hacia un futuro sostenible. La participaci\u00f3n en <a href=\"https:\/\/cop29.az\/en\/home\">COP29<\/a> ofrece una plataforma excepcional para mostrar los avances logrados, fomentando un di\u00e1logo significativo con las partes interesadas comprometidas en la lucha contra el cambio clim\u00e1tico.<\/p>\n\n\n\n<p>El proyecto ReForest tiene el honor de unirse a los 29<sup>th<\/sup> Conferencia de las Naciones Unidas sobre el Cambio Clim\u00e1tico (COP29) en Bak\u00fa (Azerbaiy\u00e1n), en un acto paralelo organizado por la <a href=\"https:\/\/euromed-economists.org\/\">Asociaci\u00f3n Euromediterr\u00e1nea de Economistas (EMEA)<\/a> en <strong>\"Financiaci\u00f3n de la agrosilvicultura: Explorando diversos esquemas de financiaci\u00f3n para el uso sostenible de la tierra\"<\/strong>.  El evento pondr\u00e1 de relieve el papel fundamental de la agrosilvicultura en el fomento de la resiliencia clim\u00e1tica y la agricultura sostenible, as\u00ed como los mecanismos de financiaci\u00f3n innovadores que pueden acelerar su adopci\u00f3n.<\/p>\n\n\n\n<p>La agrosilvicultura, que integra \u00e1rboles y arbustos en paisajes agr\u00edcolas, aporta una serie de beneficios medioambientales, sociales y econ\u00f3micos. Desde la mejora de la biodiversidad y la salud del suelo hasta la creaci\u00f3n de medios de vida estables y sostenibles, la agrosilvicultura representa un enfoque transformador del uso de la tierra. Sin embargo, la falta de financiaci\u00f3n adaptada y accesible sigue siendo un obst\u00e1culo para su adopci\u00f3n generalizada, especialmente para los peque\u00f1os agricultores que podr\u00edan beneficiarse enormemente de los beneficios a largo plazo de la agrosilvicultura. Este evento reunir\u00e1 a expertos para explorar esquemas de financiaci\u00f3n que salven esta brecha, permitiendo sistemas agr\u00edcolas m\u00e1s sostenibles y resilientes a nivel mundial.<\/p>\n\n\n\n<p><strong>Puntos destacados y principales temas de debate<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Beneficios econ\u00f3micos y medioambientales de la agrosilvicultura: El doble beneficio de la agrosilvicultura para mejorar la biodiversidad, aumentar la resistencia al cambio clim\u00e1tico y proporcionar beneficios econ\u00f3micos a largo plazo.<\/li>\n\n\n\n<li>Modelos de financiaci\u00f3n p\u00fablica y privada: El papel de los subsidios gubernamentales, las subvenciones y los marcos pol\u00edticos que incentivan la agrosilvicultura, junto con los modelos de financiaci\u00f3n verde impulsados por el sector privado, como los bonos verdes y los cr\u00e9ditos de carbono.<\/li>\n\n\n\n<li>Inversi\u00f3n de impacto y financiaci\u00f3n mixta: C\u00f3mo los inversores de impacto y los mecanismos de financiaci\u00f3n combinada pueden reducir el riesgo de las inversiones agroforestales, al tiempo que se obtienen beneficios financieros, sociales y medioambientales.<\/li>\n\n\n\n<li>Acceso de los peque\u00f1os agricultores a la financiaci\u00f3n: Abordar el d\u00e9ficit de financiaci\u00f3n de los peque\u00f1os agricultores, incluyendo la microfinanciaci\u00f3n, las cooperativas y el papel de los planes de financiaci\u00f3n comunitarios.<\/li>\n\n\n\n<li>Herramientas financieras innovadoras: Exploraci\u00f3n de herramientas como el pago por servicios ecosist\u00e9micos (PSE), la financiaci\u00f3n del carbono, los productos de seguros agroforestales y los pr\u00e9stamos vinculados a la sostenibilidad que apoyan las inversiones agroforestales a largo plazo.<\/li>\n\n\n\n<li>Retos y oportunidades para la ampliaci\u00f3n: Identificar las barreras clave para ampliar la financiaci\u00f3n de la agrosilvicultura, incluida la necesidad de horizontes de inversi\u00f3n a largo plazo, marcos normativos y alineaci\u00f3n con las normas de sostenibilidad.<\/li>\n<\/ul>\n\n\n\n<p><strong>Conozca a nuestros panelistas<\/strong><\/p>\n\n\n\n<p>Moderado por <strong>Dra. Yeganeh Forouheshfar<\/strong> de EMEA, este acto cuenta con l\u00edderes de opini\u00f3n de diversos \u00e1mbitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Martin Lukac,<\/strong> Coordinador de ReForest y profesor de la Universidad Checa de Ciencias de la Vida, Praga<\/li>\n\n\n\n<li><strong>Tiago Zibecchi,<\/strong> Investigador en EMEA<\/li>\n\n\n\n<li><strong>Enrique Doblas,<\/strong> Investigador en ecolog\u00eda y consultor del CREAF<\/li>\n\n\n\n<li><strong>Hafsa El Bekri,<\/strong> Asociado principal de estrategia ejecutiva en Positive Agenda<\/li>\n\n\n\n<li><strong>Marek Chalupnik,<\/strong> Cofundador y Director de Operaciones de DeepRoots<\/li>\n\n\n\n<li><strong>Gerry Lawson,<\/strong> Responsable de pol\u00edtica en EURAF<\/li>\n\n\n\n<li><strong>Andrea Casades\u00fas,<\/strong> Coordinador del Grupo de Investigaci\u00f3n BETA en el Centro Tecnol\u00f3gico BETA<\/li>\n<\/ul>\n\n\n\n<p><strong>\u00danase a nosotros en la COP29<\/strong><\/p>\n\n\n\n<p><strong>Date:<\/strong> 19 de noviembre de 2024<br><strong>Hora:<\/strong> 17:00 - 18:30 AZT \/ 14:00-15:30 CET<br><strong>Ubicaci\u00f3n:<\/strong> Pabell\u00f3n Mediterr\u00e1neo, Centro de Conferencias COP29, Bak\u00fa, Azerbaiy\u00e1n, y en l\u00ednea<\/p>\n\n\n\n<p>Los participantes pueden asistir en persona o virtualmente a trav\u00e9s de <a href=\"https:\/\/us02web.zoom.us\/j\/89850017454?pwd=xgdalCJEkgVxoECZM105jqzk71OwW1.1\">Zoom<\/a>.<\/p>\n\n\n\n<p>La participaci\u00f3n del proyecto ReForest en la COP29 refleja su compromiso de ampliar la agrosilvicultura como soluci\u00f3n clim\u00e1tica, especialmente en regiones vulnerables donde las comunidades se enfrentan a los efectos de fen\u00f3menos meteorol\u00f3gicos extremos.<\/p>\n\n\n\n<p>Visite el <a href=\"https:\/\/rea.ec.europa.eu\/events\/cop29-2024-2024-11-11_en\">P\u00e1gina de eventos de REA<\/a> para una visi\u00f3n completa de los proyectos financiados por la UE que participan en la COP29, o p\u00e1sese por el Pabell\u00f3n de la UE en Bak\u00fa para obtener m\u00e1s informaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>In a recent article, the European Research Executive Agency (REA) emphasises the vital role of EU-funded projects in paving the way toward a sustainable future. Participation in COP29 provides an [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/posts\/3439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/comments?post=3439"}],"version-history":[{"count":1,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/posts\/3439\/revisions"}],"predecessor-version":[{"id":3441,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/posts\/3439\/revisions\/3441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/media\/3440"}],"wp:attachment":[{"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/media?parent=3439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/categories?post=3439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agroreforest.eu\/es\/wp-json\/wp\/v2\/tags?post=3439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}