{"id":3484,"date":"2024-12-11T11:55:58","date_gmt":"2024-12-11T11:55:58","guid":{"rendered":"https:\/\/agroreforest.eu\/?p=3484"},"modified":"2024-12-11T13:42:49","modified_gmt":"2024-12-11T13:42:49","slug":"join-the-reforest-platform-a-collaborative-space-for-sustainable-agroforestry","status":"publish","type":"post","link":"https:\/\/agroreforest.eu\/de\/join-the-reforest-platform-a-collaborative-space-for-sustainable-agroforestry\/","title":{"rendered":"Treten Sie der REFOREST-Plattform bei: Ein kollaborativer Raum f\u00fcr nachhaltige Agroforstwirtschaft"},"content":{"rendered":"<p>Die Agroforstwirtschaft wird zunehmend als eine wichtige L\u00f6sung f\u00fcr eine nachhaltige Landwirtschaft und Landbewirtschaftung anerkannt. Als naturnahe und effektive Praxis bietet sie eine Reihe von \u00f6kologischen, sozialen und wirtschaftlichen Vorteilen.<\/p>\n\n\n\n<p>Die ReForest-Plattform wurde im Rahmen des ReForest-Projekts entwickelt und sorgf\u00e4ltig so konzipiert, dass sie sich \u00fcber die Projektlaufzeit hinaus selbst tr\u00e4gt und die Zusammenarbeit und Innovation in der Agroforstwirtschaft f\u00f6rdert. Ihr Ziel ist es, einen integrativen und einladenden Raum f\u00fcr die Zusammenarbeit zu schaffen, der Landwirte, Forscher, politische Entscheidungstr\u00e4ger und alle, die an einfachen und effektiven L\u00f6sungen f\u00fcr eine nachhaltige Landbewirtschaftung interessiert sind, zusammenbringt. Die Plattform ist eine Drehscheibe f\u00fcr den Wissensaustausch, den Zugang zu Ressourcen, die Beratung, den Aufbau von Gemeinschaften und die gegenseitige Unterst\u00fctzung sowie die wissenschaftliche Arbeit, die in Arbeitsgruppen organisiert ist, die wichtige Aspekte der Fortschritte in der Agroforstwirtschaft in Europa widerspiegeln.<\/p>\n\n\n\n<p><strong>Die Wissensdrehscheibe<\/strong><br>Die Plattform bietet ein umfassendes Angebot an Materialien zur Unterst\u00fctzung von Agroforstinitiativen, darunter Datens\u00e4tze, Entscheidungshilfen, Berichte, Videos, Podcasts und vieles mehr. Diese Ressourcen sind f\u00fcr alle Mitglieder zug\u00e4nglich und n\u00fctzlich, unabh\u00e4ngig davon, ob sie neu in der Agroforstwirtschaft sind oder bereits Erfahrung darin haben. Die Mitglieder werden ermutigt, Ressourcen zu teilen, um das kontinuierliche Wachstum und die Nachhaltigkeit des Hubs zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p>Die Materialien im Knowledge Hub sind dank einer einfachen und benutzerfreundlichen Suchschnittstelle leicht zu finden. Eine kurze Beschreibung jeder Ressource erm\u00f6glicht es den Nutzern, schon vor dem \u00d6ffnen zu entscheiden, ob ein Material f\u00fcr sie n\u00fctzlich sein wird. Die Kategorien sind ein einfacher Weg, um effizient zu navigieren und das Beste aus den verf\u00fcgbaren Ressourcen zu machen.<\/p>\n\n\n\n<p><strong>M\u00f6glichkeiten zur Vernetzung und Zusammenarbeit<\/strong><br>Die Mitglieder k\u00f6nnen sich mit Gleichgesinnten vernetzen und an verschiedenen Initiativen mitarbeiten. Die Plattform erm\u00f6glicht es den Nutzern, Kollegen einzuladen, pers\u00f6nliche Nachrichten zu senden und Updates in einem Haupt-Newsfeed zu ver\u00f6ffentlichen, um Informationen mit anderen Agroforst-Enthusiasten zu teilen. All dies schafft ein dynamisches, agroforstlich orientiertes soziales Netzwerk.<\/p>\n\n\n\n<p><strong>Arbeitsgruppen<\/strong><br>F\u00fcr diejenigen, die sich f\u00fcr bestimmte Agroforst-Themen interessieren, bietet die Plattform spezielle Bereiche f\u00fcr eine gezielte Zusammenarbeit. Arbeitsgruppen sind eine hervorragende M\u00f6glichkeit, Dateien auszutauschen, eingehende Diskussionen \u00fcber wichtige Themen zu f\u00fchren und an regelm\u00e4\u00dfigen Treffen teilzunehmen. Jede Gruppe wird von einem Arbeitsgruppenleiter gef\u00fchrt, der sie kontinuierlich unterst\u00fctzt und moderiert.<\/p>\n\n\n\n<p>Zu den derzeitigen Arbeitsgruppen geh\u00f6ren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ausbildung und Fortbildung von Landwirten f\u00fcr die Agroforstwirtschaft<\/li>\n\n\n\n<li>Agroforstwirtschaft - Finanzierung und Politik<\/li>\n\n\n\n<li>Parametrisierung dynamischer Werkzeuge f\u00fcr l\u00e4nder- oder laborspezifische Agroforstsysteme<\/li>\n\n\n\n<li>Institutionelle Hindernisse in europ\u00e4ischen L\u00e4ndern<\/li>\n\n\n\n<li>Agronomische Produktivit\u00e4t und Valorisierung von Agroforstprodukten in lebenden Labors<\/li>\n<\/ul>\n\n\n\n<p><strong>Veranstaltungen und Workshops<\/strong><br>Der Kalender der Plattform enth\u00e4lt Veranstaltungen, Webinare und Workshops, die sowohl vom REFOREST-Projekt als auch von externen Organisationen organisiert werden. Diese Veranstaltungen bieten die M\u00f6glichkeit, von Experten zu lernen, Ideen auszutauschen und praktische Erfahrungen mit agroforstlichen Praktiken zu sammeln.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Beitritt zum <a href=\"https:\/\/reforest.euromed-economists.org\/\">ReForest-Plattform<\/a> und werden Sie Teil einer einladenden Gemeinschaft, die sich f\u00fcr die F\u00f6rderung nachhaltiger agroforstwirtschaftlicher Praktiken einsetzt. Egal, ob Sie Landwirt, Forscher, Entscheidungstr\u00e4ger oder einfach nur leidenschaftlich an der Agroforstwirtschaft interessiert sind, diese Plattform bietet Ihnen die Werkzeuge, Ressourcen und Verbindungen, die Sie brauchen, um etwas zu bewirken.<\/p>","protected":false},"excerpt":{"rendered":"<p>Agroforestry is rapidly gaining recognition as a key solution for sustainable farming and land management. As a nature-based and effective practice, it offers a range of environmental, social, and economic [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/posts\/3484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/comments?post=3484"}],"version-history":[{"count":3,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/posts\/3484\/revisions"}],"predecessor-version":[{"id":3488,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/posts\/3484\/revisions\/3488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/media\/3485"}],"wp:attachment":[{"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/media?parent=3484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/categories?post=3484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agroreforest.eu\/de\/wp-json\/wp\/v2\/tags?post=3484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}